{"id":28904,"date":"2025-05-02T12:01:06","date_gmt":"2025-05-02T15:01:06","guid":{"rendered":"https:\/\/cndl.org.br\/varejosa\/?p=28904"},"modified":"2025-05-01T12:45:36","modified_gmt":"2025-05-01T15:45:36","slug":"dia-das-maes-deve-movimentar-3775-bilhoes-de-reais-no-varejo-78-dos-consumidores-pretendem-presentear-mostra-pesquisa-cndl-spc-brasil","status":"publish","type":"post","link":"https:\/\/cndl.org.br\/varejosa\/dia-das-maes-deve-movimentar-3775-bilhoes-de-reais-no-varejo-78-dos-consumidores-pretendem-presentear-mostra-pesquisa-cndl-spc-brasil\/","title":{"rendered":"Dia das M\u00e3es deve movimentar 37,75 bilh\u00f5es de reais no varejo; 78% dos consumidores pretendem presentear, mostra pesquisa CNDL\/SPC Brasil"},"content":{"rendered":"<p>O Dia das M\u00e3es \u00e9 a segunda data mais importante para o varejo, ficando atr\u00e1s somente do Natal. Nos pr\u00f3ximos dias o com\u00e9rcio deve receber cerca de 126,9 milh\u00f5es de consumidores que pretendem comprar algum presente. \u00c9 o que mostra uma <a href=\"https:\/\/cndl.org.br\/varejosa\/editorial\/editoriais\/pesquisa\/\" target=\"_blank\" rel=\"noopener\">pesquisa<\/a> realizada pela Confedera\u00e7\u00e3o Nacional de Dirigentes Lojistas (<a href=\"https:\/\/site.cndl.org.br\/\" target=\"_blank\" rel=\"noopener\">CNDL<\/a>) e pelo Servi\u00e7o de Prote\u00e7\u00e3o ao Cr\u00e9dito (SPC Brasil), em parceria com a Offerwise Pesquisas. De acordo com o levantamento, 78% dos consumidores devem realizar pelo menos a compra de um presente no per\u00edodo. A data deve movimentar cerca de R$ 37,75 bilh\u00f5es nos segmentos de com\u00e9rcio e servi\u00e7os. Apesar da grande movimenta\u00e7\u00e3o, a pesquisa mostra uma queda nominal de R$ 2,46 bilh\u00f5es em rela\u00e7\u00e3o ao ano passado.<\/p>\n<p>As principais presenteadas ser\u00e3o as m\u00e3es (77%), a sogra (18%) e a esposa (17%). O levantamento aponta que os consumidores pretendem gastar em m\u00e9dia R$ 298 com as compras, sendo maior o valor entre os homens (R$ 334) e entre as classes A\/B (R$ 351). De acordo com a pesquisa, 15% devem gastar de R$ 101 a R$ 200 e 11% at\u00e9 R$ 100.<\/p>\n<p>Entre aqueles que pretendem comprar presentes, 51% acreditam que as m\u00e3es merecem o presente como retribui\u00e7\u00e3o ao carinho e esfor\u00e7o dedicado, 25% consideram um gesto importante e 19% t\u00eam o costume de presentear as pessoas que gostam.<\/p>\n<p><strong>Para a maioria dos consumidores ouvidos (69%), os pre\u00e7os dos produtos este ano est\u00e3o mais caros do que ano passado.<\/strong><\/p>\n<p>De acordo com os entrevistados, 39% esperam gastar mais este ano, 37% o mesmo valor e 16% menos que no ano passado. Entre as raz\u00f5es para gastar mais, 60% pretendem comprar um presente melhor, 44% disseram que os produtos que querem comprar est\u00e3o mais caros e 31% v\u00e3o comprar mais presentes.<\/p>\n<p>Por outro lado, entre os que v\u00e3o gastar menos, 40% querem economizar, 26% ir\u00e3o comprar menos presentes este ano e 26% citaram uma situa\u00e7\u00e3o financeira dif\u00edcil.<\/p>\n<p>\u201cO Dia das M\u00e3es \u00e9 considerado pelo varejo a principal data comemorativa do primeiro semestre, e apesar da queda num\u00e9rica em rela\u00e7\u00e3o ao ano passado, sabemos que o brasileiro tem a tradi\u00e7\u00e3o de presentear. \u00c9 importante fazer pesquisa de pre\u00e7o e ficar atento ao or\u00e7amento j\u00e1 que o pa\u00eds passa por um per\u00edodo cr\u00edtico de inadimpl\u00eancia e de juros altos\u201d, destaca o presidente da CNDL, Jos\u00e9 C\u00e9sar da Costa.<\/p>\n<p><strong>Perfumes, roupas e cosm\u00e9ticos lideram o ranking dos presentes<\/strong><\/p>\n<p>A pesquisa revela que no Dia das M\u00e3es deste ano, os produtos campe\u00f5es de venda devem ser os perfumes (47%), roupas, cal\u00e7ados ou acess\u00f3rios (41%), cosm\u00e9ticos (26%), chocolates (23%) e flores (19%). E em m\u00e9dia, ser\u00e3o comprados 2 presentes.<br \/>\nOs consumidores pretendem comemorar a data principalmente na casa da m\u00e3e (43%), em sua pr\u00f3pria casa (28%) e 11% pretendem almo\u00e7ar fora em restaurantes ou bares.<\/p>\n<p>As lojas f\u00edsicas aparecem como o principal local de compras dos consumidores (80%), principalmente em shopping center (32%), shopping popular (19%), lojas de departamento (17%) e nas lojas de rua (11%).<\/p>\n<p>J\u00e1 45% pretendem fazer pelo menos uma das compras pela internet, sendo que 73% pretendem comprar em aplicativos, 69% em sites e 28% pelo Instagram.<\/p>\n<p>Os tipos de sites \/ lojas online mais citados para a compra dos presentes s\u00e3o os de varejistas internacionais (52%), seguidos dos sites de lojas de cosm\u00e9ticos e perfumes (45%) e varejistas nacionais (37%).<\/p>\n<p>Considerando os que pretendem comprar presentes em sites ou aplicativos internacionais, as principais justificativas de compra s\u00e3o: a variedade de produtos (72%), os pre\u00e7os mais baixos (61%), a qualidade dos produtos (38%) e a economia de gastos (31%).<\/p>\n<p>\u201cAs compras por aplicativos t\u00eam crescido, uma vez que as lojas e os marketplaces t\u00eam investido neste tipo de ferramenta. Apesar disso, as compras em lojas f\u00edsicas continuam sendo a prefer\u00eancia dos brasileiros, que gostam de negociar e experimentar o produto antes de levar para casa\u201d, destaca Costa.<\/p>\n<p><strong>79% pretendem fazer pesquisa de pre\u00e7o antes de comprar; PIX ser\u00e1 a forma de pagamento mais utilizada<\/strong><\/p>\n<p>A pesquisa aponta que o consumidor est\u00e1 atento aos pre\u00e7os e a grande maioria (79%) pretende fazer pesquisa antes de comprar os presentes, sobretudo pela internet (85%), seja em sites\/aplicativos (74%) e nas redes sociais (41%). 68% far\u00e3o a pesquisa de pre\u00e7os em lojas f\u00edsicas, com destaque para lojas de shoppings (47%), lojas de rua (32%) e supermercados (17%).<\/p>\n<p>Em rela\u00e7\u00e3o a forma de pagamento, 67% pretendem pagar os presentes \u00e0 vista, principalmente no PIX (46%) e cart\u00e3o de d\u00e9bito (23%). 56% citam o pagamento \u00e0 prazo, principalmente no cart\u00e3o de cr\u00e9dito parcelado (31%). A m\u00e9dia ser\u00e1 de 4 presta\u00e7\u00f5es.<\/p>\n<p><strong>32% dos que pretendem comprar presentes est\u00e3o com contas atrasadas<\/strong><\/p>\n<p>A pesquisa sinaliza que muitos dos consumidores que pretendem comprar presentes no Dia das M\u00e3es j\u00e1 extrapolaram o limite do seu or\u00e7amento: 27% admitem que costumam gastar mais do que podem com as compras na data.<\/p>\n<p>Outro comportamento preocupante, 32% dos consumidores que pretendem ir \u00e0s compras est\u00e3o com contas em atraso, sendo que 63% est\u00e3o com o nome sujo atualmente. Al\u00e9m disso, 13% reconhecem que pretendem deixar de pagar alguma conta para ir \u00e0s compras neste Dia das M\u00e3es.<\/p>\n<p>\u201cA inadimpl\u00eancia do brasileiro tem batido recorde e isso acende um alerta em rela\u00e7\u00e3o \u00e0 import\u00e2ncia do controle dos gastos nas comemora\u00e7\u00f5es. O consumidor deve priorizar o pagamento das contas antes de adquirir novas d\u00edvidas. O ato de presentear n\u00e3o pode ser mais importante do que o or\u00e7amento da fam\u00edlia. Nessa hora vale usar a criatividade e at\u00e9 mesmo dividir o pagamento do presente com outras pessoas\u201d, orienta.<\/p>\n<p>O levantamento aponta que 82% pagar\u00e3o o(s) presente(s) comprado(s) sozinhos, e 13% pretendem dividir o pagamento com mais pessoas. Entre aqueles que pretendem dividir o pagamento do(s) presente(s), 56% far\u00e3o entre irm\u00e3o(\u00e3), 34% com outros familiares e 13% com o pai.<\/p>\n<p><strong>Metodologia<\/strong><\/p>\n<p><strong>P\u00fablico-alvo:<\/strong> consumidores das 27 capitais brasileiras, homens e mulheres, com idade igual ou maior a 18 anos, de todas as classes econ\u00f4micas (excluindo analfabetos) e que pretendem realizar compras para o Dia das M\u00e3es deste ano.<\/p>\n<p><strong>M\u00e9todo de coleta:<\/strong> pesquisa realizada pela web e p\u00f3s-ponderada por sexo, idade, estado e renda.<\/p>\n<p><strong>Tamanho amostral da Pesquisa:<\/strong> 730 casos em um primeiro levantamento para identificar o percentual de pessoas com inten\u00e7\u00e3o de comprar presentes para o Dia das M\u00e3es. Em seguida, continuaram a responder o question\u00e1rio 600 casos, somente com os que tinham a inten\u00e7\u00e3o de compra para esta data. Resultando, respectivamente, uma margem de erro no geral de 3,63 p. p. e 4,0 p. p. para um intervalo de confian\u00e7a a 95%.<\/p>\n<p><strong>Per\u00edodo da coleta dos dados:<\/strong> de 01 a 10 de abril de 2025.<\/p>\n<p><strong>Testes:<\/strong> Os testes estat\u00edsticos foram realizados dentro de cada categoria \u2013 mais ou menos intenso (Sexo Mas. X Fem., Idade por faixa e Classe AB x CDE) com n\u00edvel de confian\u00e7a de 95%.<\/p>\n<p><strong>Sobre a CNDL \u2013<\/strong> Criada em 1960, a CNDL \u00e9 formada por Federa\u00e7\u00f5es de C\u00e2maras de Dirigentes Lojistas nos estados (FCDLs), C\u00e2maras de Dirigentes Lojistas nos munic\u00edpios (CDLs), SPC Brasil e CDL Jovem, entidades que, em conjunto, comp\u00f5em o Sistema CNDL. \u00c9 a principal rede representativa do varejo no pa\u00eds e tem como miss\u00e3o a defesa e o fortalecimento da livre iniciativa. Atua institucionalmente em nome de mais de 500 mil empresas, que juntas representam mais de 5% do PIB brasileiro, geram 4,6 milh\u00f5es de empregos e movimentam R$ 340 bilh\u00f5es por ano.<\/p>\n<p><strong>SPC Brasil \u2013<\/strong> H\u00e1 mais de 60 anos no mercado, o SPC Brasil possui um dos mais completos bancos de dados da Am\u00e9rica Latina, com informa\u00e7\u00f5es de cr\u00e9dito de pessoas f\u00edsicas e jur\u00eddicas. \u00c9 a plataforma de inova\u00e7\u00e3o do Sistema CNDL para apoiar empresas em conhecimento e intelig\u00eancia para cr\u00e9dito, identidade digital e solu\u00e7\u00f5es de neg\u00f3cios. Oferece servi\u00e7os que geram benef\u00edcios compartilhados para sociedade, ao auxiliar na tomada de decis\u00e3o e fomentar o acesso ao cr\u00e9dito. \u00c9 tamb\u00e9m refer\u00eancia em pesquisas, an\u00e1lises e indicadores que mapeiam o comportamento do mercado, de consumidores e empres\u00e1rios brasileiros, contribuindo para o desenvolvimento da economia do pa\u00eds.<\/p>\n<p><strong>Sobre a Offerwise &#8211;<\/strong> H\u00e1 mais de 15 anos que a Offerwise vem abordando de maneiras inovadoras a pesquisa de mercado. Com um modelo \u00fanico e pr\u00f3prio de recrutamento tem conseguido construir um dos principais pain\u00e9is de pesquisa no mundo. Evoluindo para uma empresa robusta de campo online com uso de tecnologia avan\u00e7ada. Det\u00e9m o maior e mais representativo painel da Am\u00e9rica Latina e Hisp\u00e2nico nos EUA. Os escrit\u00f3rios ao redor do mundo est\u00e3o compostos por profissionais de pesquisa de mercado que conhecem e compreendem suas culturas locais e tamb\u00e9m os consumidores que se deseja alcan\u00e7ar.<\/p>\n<p style=\"text-align: right;\"><strong>INFORMA\u00c7\u00d5ES \u00c0 IMPRENSA<\/strong><br \/>\nMarina Barbosa<br \/>\n(61) 9 8340 0257<br \/>\nimprensa@cndl.org.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Data deve levar 127 milh\u00f5es de pessoas \u00e0s compras. Perfumes, roupas e cosm\u00e9ticos ser\u00e3o os principais presentes. M\u00e9dia dos gastos ser\u00e1 de R$ 298<\/p>\n","protected":false},"author":10,"featured_media":25620,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70,2277],"tags":[1918],"class_list":["post-28904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-pesquisa","tag-dia-das-maes"],"_links":{"self":[{"href":"https:\/\/cndl.org.br\/varejosa\/wp-json\/wp\/v2\/posts\/28904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cndl.org.br\/varejosa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cndl.org.br\/varejosa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cndl.org.br\/varejosa\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cndl.org.br\/varejosa\/wp-json\/wp\/v2\/comments?post=28904"}],"version-history":[{"count":0,"href":"https:\/\/cndl.org.br\/varejosa\/wp-json\/wp\/v2\/posts\/28904\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cndl.org.br\/varejosa\/wp-json\/wp\/v2\/media\/25620"}],"wp:attachment":[{"href":"https:\/\/cndl.org.br\/varejosa\/wp-json\/wp\/v2\/media?parent=28904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cndl.org.br\/varejosa\/wp-json\/wp\/v2\/categories?post=28904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cndl.org.br\/varejosa\/wp-json\/wp\/v2\/tags?post=28904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}